{"id":6963,"date":"2015-07-17T16:13:41","date_gmt":"2015-07-17T15:13:41","guid":{"rendered":"http:\/\/195.141.44.40\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png"},"modified":"2015-07-17T16:13:41","modified_gmt":"2015-07-17T15:13:41","slug":"logo_partenaire_swisswine-logo-2","status":"inherit","type":"attachment","link":"https:\/\/www.mondialduchasselas.com\/de\/logo_partenaire_swisswine-logo-2\/","title":{"rendered":"logo_partenaire_swisswine-logo"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>logo_partenaire_swisswine-logo - Mondial du Chasselas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"logo_partenaire_swisswine-logo - Mondial du Chasselas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\" \/>\n<meta property=\"og:site_name\" content=\"Mondial du Chasselas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/MondialDuChasselas\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"40\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\",\"url\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\",\"name\":\"logo_partenaire_swisswine-logo - Mondial du Chasselas\",\"isPartOf\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\"},\"datePublished\":\"2015-07-17T15:13:41+00:00\",\"dateModified\":\"2015-07-17T15:13:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mondialduchasselas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"logo_partenaire_swisswine-logo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\",\"url\":\"https:\/\/www.mondialduchasselas.com\/\",\"name\":\"Mondial du Chasselas\",\"description\":\"Le Chasselas, un c\u00e9page plus actuel que jamais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"logo_partenaire_swisswine-logo - Mondial du Chasselas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","og_locale":"de_DE","og_type":"article","og_title":"logo_partenaire_swisswine-logo - Mondial du Chasselas","og_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","og_site_name":"Mondial du Chasselas","article_publisher":"http:\/\/www.facebook.com\/MondialDuChasselas\/","og_image":[{"width":40,"height":50,"url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","name":"logo_partenaire_swisswine-logo - Mondial du Chasselas","isPartOf":{"@id":"https:\/\/www.mondialduchasselas.com\/#website"},"datePublished":"2015-07-17T15:13:41+00:00","dateModified":"2015-07-17T15:13:41+00:00","breadcrumb":{"@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mondialduchasselas.com\/"},{"@type":"ListItem","position":2,"name":"logo_partenaire_swisswine-logo"}]},{"@type":"WebSite","@id":"https:\/\/www.mondialduchasselas.com\/#website","url":"https:\/\/www.mondialduchasselas.com\/","name":"Mondial du Chasselas","description":"Le Chasselas, un c\u00e9page plus actuel que jamais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png'><img width=\"40\" height=\"50\" src=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":40,"height":50,"file":"2015\/07\/logo_partenaire_swisswine-logo.png","sizes":{},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/07\/logo_partenaire_swisswine-logo.png","_links":{"self":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media\/6963"}],"collection":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/comments?post=6963"}]}}