{"id":7122,"date":"2015-11-20T09:11:10","date_gmt":"2015-11-20T08:11:10","guid":{"rendered":"http:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg"},"modified":"2015-11-20T09:11:10","modified_gmt":"2015-11-20T08:11:10","slug":"chasselas-for-ever-photos-2","status":"inherit","type":"attachment","link":"https:\/\/www.mondialduchasselas.com\/de\/chasselas-for-ever-photos-2\/","title":{"rendered":"chasselas for ever photos"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>chasselas for ever photos - Mondial du Chasselas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"chasselas for ever photos - Mondial du Chasselas\" \/>\n<meta property=\"og:description\" content=\"Photos: Florian Burion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"Mondial du Chasselas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/MondialDuChasselas\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\",\"url\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\",\"name\":\"chasselas for ever photos - Mondial du Chasselas\",\"isPartOf\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\"},\"datePublished\":\"2015-11-20T08:11:10+00:00\",\"dateModified\":\"2015-11-20T08:11:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mondialduchasselas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"chasselas for ever photos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\",\"url\":\"https:\/\/www.mondialduchasselas.com\/\",\"name\":\"Mondial du Chasselas\",\"description\":\"Le Chasselas, un c\u00e9page plus actuel que jamais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chasselas for ever photos - Mondial du Chasselas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","og_locale":"de_DE","og_type":"article","og_title":"chasselas for ever photos - Mondial du Chasselas","og_description":"Photos: Florian Burion","og_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","og_site_name":"Mondial du Chasselas","article_publisher":"http:\/\/www.facebook.com\/MondialDuChasselas\/","og_image":[{"width":513,"height":480,"url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","name":"chasselas for ever photos - Mondial du Chasselas","isPartOf":{"@id":"https:\/\/www.mondialduchasselas.com\/#website"},"datePublished":"2015-11-20T08:11:10+00:00","dateModified":"2015-11-20T08:11:10+00:00","breadcrumb":{"@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mondialduchasselas.com\/"},{"@type":"ListItem","position":2,"name":"chasselas for ever photos"}]},{"@type":"WebSite","@id":"https:\/\/www.mondialduchasselas.com\/#website","url":"https:\/\/www.mondialduchasselas.com\/","name":"Mondial du Chasselas","description":"Le Chasselas, un c\u00e9page plus actuel que jamais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg'><img width=\"300\" height=\"281\" src=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-300x281.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-300x281.jpeg 300w, https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg 513w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Photos: Florian Burion<\/p>\n"},"caption":{"rendered":"<p>Photos: Florian Burion<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":513,"height":480,"file":"2015\/11\/chasselas-for-ever-photos.jpeg","sizes":{"thumbnail":{"file":"chasselas-for-ever-photos-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-150x150.jpeg"},"medium":{"file":"chasselas-for-ever-photos-300x281.jpeg","width":300,"height":281,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-300x281.jpeg"},"narrow-featured-image-full":{"file":"chasselas-for-ever-photos-513x290.jpeg","width":513,"height":290,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-513x290.jpeg"},"narrow-featured-image":{"file":"chasselas-for-ever-photos-400x300.jpeg","width":400,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-400x300.jpeg"},"wide-featured-image-full":{"file":"chasselas-for-ever-photos-513x300.jpeg","width":513,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-513x300.jpeg"},"wide-featured-image":{"file":"chasselas-for-ever-photos-513x300.jpeg","width":513,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-513x300.jpeg"},"featured-page":{"file":"chasselas-for-ever-photos-315x145.jpeg","width":315,"height":145,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos-315x145.jpeg"},"full":{"file":"chasselas-for-ever-photos.jpeg","width":513,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2015\/11\/chasselas-for-ever-photos.jpeg","_links":{"self":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media\/7122"}],"collection":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/comments?post=7122"}]}}