{"id":7513,"date":"2022-11-27T05:41:03","date_gmt":"2022-11-27T04:41:03","guid":{"rendered":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg"},"modified":"2022-11-27T05:41:03","modified_gmt":"2022-11-27T04:41:03","slug":"sur-la-piste-du-chasselas-de-cover-solo_01-page-001-2","status":"inherit","type":"attachment","link":"https:\/\/www.mondialduchasselas.com\/de\/sur-la-piste-du-chasselas-de-cover-solo_01-page-001-2\/","title":{"rendered":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Mondial du Chasselas\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/MondialDuChasselas\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\",\"url\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\",\"name\":\"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas\",\"isPartOf\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\"},\"datePublished\":\"2022-11-27T04:41:03+00:00\",\"dateModified\":\"2022-11-27T04:41:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mondialduchasselas.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mondialduchasselas.com\/#website\",\"url\":\"https:\/\/www.mondialduchasselas.com\/\",\"name\":\"Mondial du Chasselas\",\"description\":\"Le Chasselas, un c\u00e9page plus actuel que jamais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","og_locale":"de_DE","og_type":"article","og_title":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas","og_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","og_site_name":"Mondial du Chasselas","article_publisher":"http:\/\/www.facebook.com\/MondialDuChasselas\/","og_image":[{"width":1240,"height":1754,"url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","name":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001 - Mondial du Chasselas","isPartOf":{"@id":"https:\/\/www.mondialduchasselas.com\/#website"},"datePublished":"2022-11-27T04:41:03+00:00","dateModified":"2022-11-27T04:41:03+00:00","breadcrumb":{"@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mondialduchasselas.com\/"},{"@type":"ListItem","position":2,"name":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001"}]},{"@type":"WebSite","@id":"https:\/\/www.mondialduchasselas.com\/#website","url":"https:\/\/www.mondialduchasselas.com\/","name":"Mondial du Chasselas","description":"Le Chasselas, un c\u00e9page plus actuel que jamais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mondialduchasselas.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg'><img width=\"212\" height=\"300\" src=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-212x300.jpg 212w, https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-724x1024.jpg 724w, https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-768x1086.jpg 768w, https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-1086x1536.jpg 1086w, https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg 1240w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1240,"height":1754,"file":"2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","filesize":447719,"sizes":{"medium":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-212x300.jpg","width":212,"height":300,"filesize":22969,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-212x300.jpg"},"large":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-724x1024.jpg","width":724,"height":1024,"filesize":185894,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-724x1024.jpg"},"thumbnail":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-150x150.jpg","width":150,"height":150,"filesize":10675,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-150x150.jpg"},"medium_large":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-768x1086.jpg","width":768,"height":1086,"filesize":204607,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-768x1086.jpg"},"1536x1536":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-1086x1536.jpg","width":1086,"height":1536,"filesize":365188,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-1086x1536.jpg"},"narrow-featured-image-full":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-630x290.jpg","width":630,"height":290,"filesize":54881,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-630x290.jpg"},"narrow-featured-image":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-400x300.jpg","width":400,"height":300,"filesize":40627,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-400x300.jpg"},"wide-featured-image-full":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-960x300.jpg","width":960,"height":300,"filesize":74775,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-960x300.jpg"},"wide-featured-image":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-600x300.jpg","width":600,"height":300,"filesize":54980,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-600x300.jpg"},"featured-page":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-315x145.jpg","width":315,"height":145,"filesize":17264,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001-315x145.jpg"},"full":{"file":"Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","width":1240,"height":1754,"mime_type":"image\/jpeg","source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.mondialduchasselas.com\/wp-content\/uploads\/2022\/11\/Sur-la-piste-du-chasselas-DE-Cover-Solo_01-page-001.jpg","_links":{"self":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media\/7513"}],"collection":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mondialduchasselas.com\/de\/wp-json\/wp\/v2\/comments?post=7513"}]}}